{"id":368,"date":"2020-01-28T10:19:40","date_gmt":"2020-01-28T09:19:40","guid":{"rendered":"https:\/\/www.lagabriotte.fr\/?page_id=368"},"modified":"2020-01-28T10:24:25","modified_gmt":"2020-01-28T09:24:25","slug":"mentions-legales","status":"publish","type":"page","link":"https:\/\/www.lagabriotte.fr\/index.php\/mentions-legales\/","title":{"rendered":"Mentions l\u00e9gales"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"368\" class=\"elementor elementor-368\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-2a85ece elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"43216\" data-id=\"2a85ece\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85dd2fc\" data-eae-slider=\"24730\" data-id=\"85dd2fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25c9a26 elementor-widget elementor-widget-heading\" data-id=\"25c9a26\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mentions l\u00e9gales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abcb8e2 elementor-widget elementor-widget-text-editor\" data-id=\"abcb8e2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\">Conform\u00e9ment aux dispositions des articles 6-III et 19 de la Loi n\u00b0 2004-575 du 21 juin 2004 pour la Confiance dans l&rsquo;\u00e9conomie num\u00e9rique, dite L.C.E.N., nous portons \u00e0 la connaissance des utilisateurs et visiteurs du site : <a href=\"http:\/\/www.lagabriotte.fr\" target=\"_blank\" rel=\"noopener\">www.lagabriotte.fr<\/a> les informations suivantes :<\/p><p style=\"text-align: justify;\"><strong>1. Informations l\u00e9gales :<\/strong><\/p><p style=\"text-align: justify;\">Statut du propri\u00e9taire : <strong>Exploitant individuel<\/strong><br \/>Le Propri\u00e9taire est : <strong>Karen LORET<br \/><\/strong>SIRET : <strong>837 648 039 00027<br \/><\/strong>Adresse postale du propri\u00e9taire : <strong>6 B Rue de la Grande Ile 44120 Vertou<\/strong><\/p><p>Le Cr\u00e9ateur du site est : <strong>comlelephant.com<\/strong><br \/>Le Responsable de la publication est : <strong>Karen LORET<\/strong><br \/>Contacter le responsable de la publication : <strong>karen@lagabriotte.fr<\/strong><br \/>Le responsable de la publication est une<strong> personne physique<\/strong><\/p><p>Le Webmaster est : <strong>Com L&rsquo;El\u00e9phant<\/strong><br \/>Contacter le Webmaster : <strong><a href=\"mailto:webmaster@comlelephant.com?subject=Contact a partir des mentions l\u00c3\u00a9gales via le site www.lagabriotte.fr\">webmaster@comlelephant.com<\/a><\/strong><br \/>L\u2019hebergeur du site est : <strong>OVH 2 rue Kellermann 59100 ROUBAIX<\/strong><\/p><p style=\"text-align: justify;\"><strong>2. Pr\u00e9sentation et principe :<\/strong><\/p><p style=\"text-align: justify;\">Est d\u00e9sign\u00e9 ci-apr\u00e8s : <strong>Utilisateur<\/strong>, tout internaute se connectant et utilisant le site susnomm\u00e9 : <a href=\"http:\/\/www.lagabriotte.fr\" target=\"_blank\" rel=\"noopener\">www.lagabriotte.fr<\/a>.<br \/>Le site <strong>www.lagabriotte.fr<\/strong> regroupe un ensemble de services, dans l&rsquo;\u00e9tat, mis \u00e0 la disposition des utilisateurs. Il est ici pr\u00e9cis\u00e9 que ces derniers doivent rester courtois et faire preuve de bonne foi tant envers les autres utilisateurs qu&rsquo;envers le webmaster du site www.lagabriotte.fr. Le site www.lagabriotte.fr est mis \u00e0 jour r\u00e9guli\u00e8rement par Com L&rsquo;El\u00e9phant.<br \/>Karen LORET s\u2019efforce de fournir sur le site www.lagabriotte.fr des informations les plus pr\u00e9cises possibles (sous r\u00e9serve de modifications apport\u00e9es depuis leur mise en ligne), mais ne saurait garantir l&rsquo;exactitude, la compl\u00e9tude et l&rsquo;actualit\u00e9 des informations diffus\u00e9es sur son site, qu\u2019elles soient de son fait ou du fait des tiers partenaires qui lui fournissent ces informations. En cons\u00e9quence, l&rsquo;utilisateur reconna\u00eet utiliser ces informations donn\u00e9es (\u00e0 titre indicatif, non exhaustives et susceptibles d&rsquo;\u00e9voluer) sous sa responsabilit\u00e9 exclusive.<\/p><p style=\"text-align: justify;\"><strong>3. Accessibilit\u00e9 :<\/strong><\/p><p>Le site www.lagabriotte.fr est par principe accessible aux utilisateurs 24\/24h, 7\/7j, sauf interruption, programm\u00e9e ou non, pour les besoins de sa maintenance ou en cas de force majeure. En cas d\u2019impossibilit\u00e9 d\u2019acc\u00e8s au service, www.lagabriotte.fr s\u2019engage \u00e0 faire son maximum afin de r\u00e9tablir l\u2019acc\u00e8s au service et s\u2019efforcera alors de communiquer pr\u00e9alablement aux utilisateurs les dates et heures de l\u2019intervention. N\u2019\u00e9tant soumis qu\u2019\u00e0 une obligation de moyen, www.lagabriotte.fr ne saurait \u00eatre tenu pour responsable de tout dommage, quelle qu\u2019en soit la nature, r\u00e9sultant d\u2019une indisponibilit\u00e9 du service.<\/p><p style=\"text-align: justify;\"><strong>4. Propri\u00e9t\u00e9 intellectuelle :<\/strong><\/p><p style=\"text-align: justify;\">Karen LORET est propri\u00e9taire exclusif de tous les droits de propri\u00e9t\u00e9 intellectuelle ou d\u00e9tient les droits d\u2019usage sur tous les \u00e9l\u00e9ments accessibles sur le site, tant sur la structure que sur les textes, images, graphismes, logo, ic\u00f4nes, sons, logiciels\u2026<br \/>Toute reproduction totale ou partielle du site www.lagabriotte.fr, repr\u00e9sentation, modification, publication, adaptation totale ou partielle de l&rsquo;un quelconque de ces \u00e9l\u00e9ments, quel que soit le moyen ou le proc\u00e9d\u00e9 utilis\u00e9, est interdite, sauf autorisation \u00e9crite pr\u00e9alable de Karen LORET, propri\u00e9taire du site \u00e0 l&#8217;email : webmaster@comlelephant.com, \u00e0 d\u00e9faut elle sera consid\u00e9r\u00e9e comme constitutive d\u2019une contrefa\u00e7on et passible de poursuite conform\u00e9ment aux dispositions des articles L.335-2 et suivants du Code de Propri\u00e9t\u00e9 Intellectuelle.<\/p><p style=\"text-align: justify;\"><strong>5. Liens hypertextes et cookies :<\/strong><\/p><p>Le site www.lagabriotte.fr contient un certain nombre de liens hypertextes vers d\u2019autres sites (partenaires, informations \u2026) mis en place avec l\u2019autorisation de Karen LORET. Cependant, Karen LORET n\u2019a pas la possibilit\u00e9 de v\u00e9rifier l&rsquo;ensemble du contenu des sites ainsi visit\u00e9s et d\u00e9cline donc toute responsabilit\u00e9 de ce fait quand aux risques \u00e9ventuels de contenus illicites.<br \/>L\u2019utilisateur est inform\u00e9 que lors de ses visites sur le site www.lagabriotte.fr, un ou des cookies sont susceptibles de s\u2019installer automatiquement sur son ordinateur par l&rsquo;interm\u00e9diaire de son logiciel de navigation. Un cookie est un bloc de donn\u00e9es qui ne permet pas d&rsquo;identifier l&rsquo;utilisateur, mais qui enregistre des informations relatives \u00e0 la navigation de celui-ci sur le site. <br \/>Le param\u00e9trage du logiciel de navigation permet d\u2019informer de la pr\u00e9sence de cookie et \u00e9ventuellement, de la refuser de la mani\u00e8re d\u00e9crite \u00e0 l\u2019adresse suivante : <a href=\"http:\/\/www.cnil.fr\">www.cnil.fr<\/a>. L\u2019utilisateur peut toutefois configurer le navigateur de son ordinateur pour refuser l\u2019installation des cookies, sachant que le refus d&rsquo;installation d&rsquo;un cookie peut entra\u00eener l\u2019impossibilit\u00e9 d\u2019acc\u00e9der \u00e0 certains services. Pour tout bloquage des cookies, tapez dans votre moteur de recherche : bloquage des cookies sous IE ou firefox et suivez les instructions en fonction de votre version.<\/p><p style=\"text-align: justify;\"><strong>6. Protection des biens et des personnes &#8211; gestion des donn\u00e9es personnelles :<\/strong><\/p><p>En France, les donn\u00e9es personnelles sont notamment prot\u00e9g\u00e9es par la loi n\u00b0 78-87 du 6 janvier 1978, la loi n\u00b0 2004-801 du 6 ao\u00fbt 2004, l&rsquo;article L. 226-13 du Code p\u00e9nal et la Directive Europ\u00e9enne du 24 octobre 1995.<\/p><p style=\"text-align: justify;\">Sur le site www.lagabriotte.fr, Karen LORET ne collecte des informations personnelles ( suivant l&rsquo;article 4 loi n\u00b078-17 du 06 janvier 1978) relatives \u00e0 l&rsquo;utilisateur que pour le besoin de certains services propos\u00e9s par le site www.lagabriotte.fr. L&rsquo;utilisateur fournit ces informations en toute connaissance de cause, notamment lorsqu&rsquo;il proc\u00e8de par lui-m\u00eame \u00e0 leur saisie. Il est alors pr\u00e9cis\u00e9 \u00e0 l&rsquo;utilisateur du site www.lagabriotte.fr l\u2019obligation ou non de fournir ces informations.<br \/>Conform\u00e9ment aux dispositions des articles 38 et suivants de la loi 78-17 du 6 janvier 1978 relative \u00e0 l\u2019informatique, aux fichiers et aux libert\u00e9s, tout utilisateur dispose d\u2019un droit d\u2019acc\u00e8s, de rectification, de suppression et d\u2019opposition aux donn\u00e9es personnelles le concernant. Pour l\u2019exercer, adressez votre demande \u00e0 www.lagabriotte.fr par email : <strong><a href=\"mailto:webmaster@comlelephant.com?subject=Contact \u00ef\u00bf\u00bd partir des mentions l\u00ef\u00bf\u00bdgales via le site www.lagabriotte.fr\">karen@lagabriotte.fr<\/a><\/strong> ou par \u00e9crit d\u00fbment sign\u00e9e, accompagn\u00e9e d\u2019une copie du titre d\u2019identit\u00e9 avec signature du titulaire de la pi\u00e8ce, en pr\u00e9cisant l\u2019adresse \u00e0 laquelle la r\u00e9ponse doit \u00eatre envoy\u00e9e.<\/p><p style=\"text-align: justify;\">Aucune information personnelle de l&rsquo;utilisateur du site www.lagabriotte.fr n&rsquo;est publi\u00e9e \u00e0 l&rsquo;insu de l&rsquo;utilisateur, \u00e9chang\u00e9e, transf\u00e9r\u00e9e, c\u00e9d\u00e9e ou vendue sur un support quelconque \u00e0 des tiers. Seule l&rsquo;hypoth\u00e8se du rachat du site www.lagabriotte.fr et de ses droits autorise Karen LORET \u00e0 transmettre les dites informations \u00e0 l&rsquo;\u00e9ventuel acqu\u00e9reur qui serait \u00e0 son tour tenu \u00e0 la m\u00eame obligation de conservation et de modification des donn\u00e9es vis \u00e0 vis de l&rsquo;utilisateur du site www.lagabriotte.fr.<br \/>Le site www.lagabriotte.fr est en conformit\u00e9 avec le RGPD voir notre politique RGPD www.lagabriotte.fr\/cgv.<\/p><p style=\"text-align: justify;\">Les bases de donn\u00e9es sont prot\u00e9g\u00e9es par les dispositions de la loi du 1er juillet 1998 transposant la directive 96\/9 du 11 mars 1996 relative \u00e0 la protection juridique des bases de donn\u00e9es.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Mentions l\u00e9gales Conform\u00e9ment aux dispositions des articles 6-III et 19 de la Loi n\u00b0 2004-575 du 21 juin 2004 pour la Confiance dans l&rsquo;\u00e9conomie num\u00e9rique, dite L.C.E.N., nous portons \u00e0 la connaissance des utilisateurs et visiteurs du site : www.lagabriotte.fr les informations suivantes : 1. Informations l\u00e9gales : Statut du propri\u00e9taire : Exploitant individuelLe Propri\u00e9taire [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-368","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mentions l\u00e9gales - La Gabriotte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lagabriotte.fr\/index.php\/mentions-legales\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mentions l\u00e9gales - La Gabriotte\" \/>\n<meta property=\"og:description\" content=\"Mentions l\u00e9gales Conform\u00e9ment aux dispositions des articles 6-III et 19 de la Loi n\u00b0 2004-575 du 21 juin 2004 pour la Confiance dans l&rsquo;\u00e9conomie num\u00e9rique, dite L.C.E.N., nous portons \u00e0 la connaissance des utilisateurs et visiteurs du site : www.lagabriotte.fr les informations suivantes : 1. Informations l\u00e9gales : Statut du propri\u00e9taire : Exploitant individuelLe Propri\u00e9taire [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lagabriotte.fr\/index.php\/mentions-legales\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gabriotte\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-28T09:24:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lagabriotte.fr\/index.php\/mentions-legales\/\",\"url\":\"https:\/\/www.lagabriotte.fr\/index.php\/mentions-legales\/\",\"name\":\"Mentions l\u00e9gales - La Gabriotte\",\"isPartOf\":{\"@id\":\"https:\/\/www.lagabriotte.fr\/#website\"},\"datePublished\":\"2020-01-28T09:19:40+00:00\",\"dateModified\":\"2020-01-28T09:24:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lagabriotte.fr\/index.php\/mentions-legales\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lagabriotte.fr\/index.php\/mentions-legales\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lagabriotte.fr\/index.php\/mentions-legales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lagabriotte.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mentions l\u00e9gales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lagabriotte.fr\/#website\",\"url\":\"https:\/\/www.lagabriotte.fr\/\",\"name\":\"La Gabriotte\",\"description\":\"Plats \u00e0 Emporter \u00e0 Nantes\",\"publisher\":{\"@id\":\"https:\/\/www.lagabriotte.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lagabriotte.fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lagabriotte.fr\/#organization\",\"name\":\"La Gabriotte\",\"url\":\"https:\/\/www.lagabriotte.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lagabriotte.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lagabriotte.fr\/wp-content\/uploads\/2019\/11\/la-gabriotte-plats-a-emporter-a-nantes.jpg\",\"contentUrl\":\"https:\/\/www.lagabriotte.fr\/wp-content\/uploads\/2019\/11\/la-gabriotte-plats-a-emporter-a-nantes.jpg\",\"width\":512,\"height\":512,\"caption\":\"La Gabriotte\"},\"image\":{\"@id\":\"https:\/\/www.lagabriotte.fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mentions l\u00e9gales - La Gabriotte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lagabriotte.fr\/index.php\/mentions-legales\/","og_locale":"fr_FR","og_type":"article","og_title":"Mentions l\u00e9gales - La Gabriotte","og_description":"Mentions l\u00e9gales Conform\u00e9ment aux dispositions des articles 6-III et 19 de la Loi n\u00b0 2004-575 du 21 juin 2004 pour la Confiance dans l&rsquo;\u00e9conomie num\u00e9rique, dite L.C.E.N., nous portons \u00e0 la connaissance des utilisateurs et visiteurs du site : www.lagabriotte.fr les informations suivantes : 1. Informations l\u00e9gales : Statut du propri\u00e9taire : Exploitant individuelLe Propri\u00e9taire [&hellip;]","og_url":"https:\/\/www.lagabriotte.fr\/index.php\/mentions-legales\/","og_site_name":"La Gabriotte","article_modified_time":"2020-01-28T09:24:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lagabriotte.fr\/index.php\/mentions-legales\/","url":"https:\/\/www.lagabriotte.fr\/index.php\/mentions-legales\/","name":"Mentions l\u00e9gales - La Gabriotte","isPartOf":{"@id":"https:\/\/www.lagabriotte.fr\/#website"},"datePublished":"2020-01-28T09:19:40+00:00","dateModified":"2020-01-28T09:24:25+00:00","breadcrumb":{"@id":"https:\/\/www.lagabriotte.fr\/index.php\/mentions-legales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lagabriotte.fr\/index.php\/mentions-legales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lagabriotte.fr\/index.php\/mentions-legales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lagabriotte.fr\/"},{"@type":"ListItem","position":2,"name":"Mentions l\u00e9gales"}]},{"@type":"WebSite","@id":"https:\/\/www.lagabriotte.fr\/#website","url":"https:\/\/www.lagabriotte.fr\/","name":"La Gabriotte","description":"Plats \u00e0 Emporter \u00e0 Nantes","publisher":{"@id":"https:\/\/www.lagabriotte.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lagabriotte.fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lagabriotte.fr\/#organization","name":"La Gabriotte","url":"https:\/\/www.lagabriotte.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lagabriotte.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.lagabriotte.fr\/wp-content\/uploads\/2019\/11\/la-gabriotte-plats-a-emporter-a-nantes.jpg","contentUrl":"https:\/\/www.lagabriotte.fr\/wp-content\/uploads\/2019\/11\/la-gabriotte-plats-a-emporter-a-nantes.jpg","width":512,"height":512,"caption":"La Gabriotte"},"image":{"@id":"https:\/\/www.lagabriotte.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lagabriotte.fr\/index.php\/wp-json\/wp\/v2\/pages\/368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lagabriotte.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lagabriotte.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lagabriotte.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lagabriotte.fr\/index.php\/wp-json\/wp\/v2\/comments?post=368"}],"version-history":[{"count":3,"href":"https:\/\/www.lagabriotte.fr\/index.php\/wp-json\/wp\/v2\/pages\/368\/revisions"}],"predecessor-version":[{"id":371,"href":"https:\/\/www.lagabriotte.fr\/index.php\/wp-json\/wp\/v2\/pages\/368\/revisions\/371"}],"wp:attachment":[{"href":"https:\/\/www.lagabriotte.fr\/index.php\/wp-json\/wp\/v2\/media?parent=368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}